{"id":24519,"date":"2023-08-25T19:03:55","date_gmt":"2023-08-25T22:03:55","guid":{"rendered":"https:\/\/www.ejercito.mil.uy\/?p=24519"},"modified":"2023-08-30T09:14:35","modified_gmt":"2023-08-30T12:14:35","slug":"198o-aniversario-de-la-declaratoria-de-la-independencia","status":"publish","type":"post","link":"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/","title":{"rendered":"198\u00ba aniversario de la Declaratoria de la Independencia"},"content":{"rendered":"\n<p class=\"has-small-font-size\">25.08.2023 &#8211; Florida<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background has-medium-font-size\" style=\"background-color:#b78600\">Hoy, se realizaron los actos protocolares por el \ud835\udfcf\ud835\udfd7\ud835\udfd6\u00ba \ud835\udc1a\ud835\udc27\ud835\udc22\ud835\udc2f\ud835\udc1e\ud835\udc2b\ud835\udc2c\ud835\udc1a\ud835\udc2b\ud835\udc22\ud835\udc28 \ud835\udc1d\ud835\udc1e \ud835\udc25\ud835\udc1a \ud835\udc03\ud835\udc1e\ud835\udc1c\ud835\udc25\ud835\udc1a\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc28\ud835\udc2b\ud835\udc22\ud835\udc1a \ud835\udc1d\ud835\udc1e \ud835\udc25\ud835\udc1a \ud835\udc08\ud835\udc27\ud835\udc1d\ud835\udc1e\ud835\udc29\ud835\udc1e\ud835\udc27\ud835\udc1d\ud835\udc1e\ud835\udc27\ud835\udc1c\ud835\udc22\ud835\udc1a.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Unidades de todo el pa\u00eds desfilaron en sus Departamentos. El acto central se realiz\u00f3 en la ciudad de Florida, en la Piedra Alta, lugar declarado \u00abAltar de la patria\u00bb, porque all\u00ed fue en donde se proclam\u00f3 la Independencia de nuestro pa\u00eds.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel alignfull\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-caption-style-dark has-horizontal-gutter has-no-thumbnails\"><div class=\"has-carousel has-carousel-xlrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:false,&quot;freeMode&quot;:false,&quot;loop&quot;:false,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:1,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:550px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24521\" data-id=\"24521\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24521\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-2-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-2-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-2-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24522\" data-id=\"24522\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24522\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-3-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-3-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-3-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24523\" data-id=\"24523\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24523\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-4-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-4-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-4-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-4-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24524\" data-id=\"24524\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24524\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-5-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-5-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-5-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Acto-protocolar-en-la-Piedra-Alta-25AGO.23-5.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><\/button><button class=\"nav-button__next\" id=\"12345-next\"><\/button><\/div><\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Posteriormente, se desarroll\u00f3 el desfile c\u00edvico militar en el cual marcharon <a><\/a>efectivos de Unidades de Tradici\u00f3n Hist\u00f3rica, alumnos de la Escuela Militar y <a href=\"https:\/\/www.facebook.com\/LiceoMilitaruy?__cft__[0]=AZX6wRbD4X1Wly_wMVZdc06NyOyl7bz3rDLF-3GyHfyELodYPJarvs_oZPqEI9Bu0UFsbEQPFiXyQHd8XuQOf_4vpd83UVqIqalcL-sbjUlvrdwLvv6oRyylVT2ObzZ7RBSAkS7MlC4i7Lily-zdOdTfGCfF99lMitlmaZq-GGRbyy_hwdoxqYGo1KV2gf6L_dM&amp;__tn__=-]K-R\">Liceo Militar \u00abGeneral Artigas\u00bb<\/a>, Unidades dependientes de la Divisi\u00f3n de Ej\u00e9rcito II y bandas militares.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Ambos actos, fueron encabezados por el Sr. Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><em>Ver nota a partir del minuto 00:56 en la edici\u00f3n 25 del informativo Ej\u00e9rcito del Uruguay &#8211;<a rel=\"noreferrer noopener\" href=\"https:\/\/youtu.be\/XmJ3dvcaweM?fbclid=IwAR1-41HiUWTQxOduvuq0t4HSWcih4mRkIbDbFrtHeOWKsgkASkM3mqPzwNE\" target=\"_blank\">https:\/\/youtu.be\/XmJ3dvcaweM<\/a><\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">\u00a1Compartimos algunas im\u00e1genes de este gran festejo!<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel alignfull\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-caption-style-dark has-horizontal-gutter has-no-thumbnails\"><div class=\"has-carousel has-carousel-xlrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:false,&quot;freeMode&quot;:false,&quot;loop&quot;:false,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:1,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:550px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24552\" data-id=\"24552\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24552\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-14-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-14-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-14-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-14.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24553\" data-id=\"24553\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24553\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO23-15-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO23-15-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO23-15-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO23-15.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24554\" data-id=\"24554\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24554\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-16-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-16-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-16-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-16.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><\/button><button class=\"nav-button__next\" id=\"12345-next\"><\/button><\/div><\/div><\/div>\n\n\n\n<p class=\"has-medium-font-size\">alumnos de la <a href=\"https:\/\/www.facebook.com\/EscuelaMilitarUruguay\" data-type=\"URL\" data-id=\"https:\/\/www.facebook.com\/EscuelaMilitarUruguay\">Escuela Militar<\/a> y <a href=\"https:\/\/www.facebook.com\/LiceoMilitaruy?__cft__[0]=AZX6wRbD4X1Wly_wMVZdc06NyOyl7bz3rDLF-3GyHfyELodYPJarvs_oZPqEI9Bu0UFsbEQPFiXyQHd8XuQOf_4vpd83UVqIqalcL-sbjUlvrdwLvv6oRyylVT2ObzZ7RBSAkS7MlC4i7Lily-zdOdTfGCfF99lMitlmaZq-GGRbyy_hwdoxqYGo1KV2gf6L_dM&amp;__tn__=-]K-R\">Liceo Militar \u00abGeneral Artigas\u00bb<\/a><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel alignfull\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-caption-style-dark has-horizontal-gutter has-no-thumbnails\"><div class=\"has-carousel has-carousel-xlrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:false,&quot;freeMode&quot;:false,&quot;loop&quot;:false,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:1,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:550px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24551\" data-id=\"24551\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-13\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-13-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-13-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-13-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-13.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24544\" data-id=\"24544\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-1-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-1-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-1-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-1-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-1-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24562\" data-id=\"24562\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-23\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-23-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-23-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-23-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-23.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24546\" data-id=\"24546\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-3-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-3-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-3-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-3-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-3-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24547\" data-id=\"24547\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-4-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-4-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-4-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-4-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-4-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24545\" data-id=\"24545\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-2-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-2-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-2-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-2-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-2-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24550\" data-id=\"24550\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-12-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-12-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-12-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-12-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-12-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24548\" data-id=\"24548\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-5-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-5-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-5-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-5-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-5-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24549\" data-id=\"24549\" data-link=\"https:\/\/www.ejercito.mil.uy\/index.php\/2023\/08\/25\/198o-aniversario-de-la-declaratoria-de-la-independencia\/desfile-civico-militar-en-florida-25ago-23-6-1\/\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-6-1-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-6-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-6-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-6-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><\/button><button class=\"nav-button__next\" id=\"12345-next\"><\/button><\/div><\/div><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Unidades de Tradici\u00f3n Hist\u00f3rica<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel alignfull\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-caption-style-dark has-horizontal-gutter has-no-thumbnails\"><div class=\"has-carousel has-carousel-xlrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:false,&quot;freeMode&quot;:false,&quot;loop&quot;:false,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:1,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:550px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24538\" data-id=\"24538\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24538\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-10-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-10-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-10-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-10.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24539\" data-id=\"24539\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24539\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-17-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-17-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-17-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-17.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24541\" data-id=\"24541\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24541\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-19-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-19-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-19-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-19.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24542\" data-id=\"24542\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24542\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-20-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-20-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-20-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-20.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24543\" data-id=\"24543\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24543\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-21-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-21-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-21-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-21.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24540\" data-id=\"24540\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24540\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-18-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-18-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-18-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-18.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24535\" data-id=\"24535\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24535\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-7-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-7-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-7-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-7.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24536\" data-id=\"24536\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24536\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-8-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-8-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-8-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-8.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-24537\" data-id=\"24537\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=24537\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-9-1024x683.jpg\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-9-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-9-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2023\/08\/Desfile-Civico-Militar-en-Florida-25AGO.23-9.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><\/button><button class=\"nav-button__next\" id=\"12345-next\"><\/button><\/div><\/div><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Unidades dependientes de la Divisi\u00f3n de Ej\u00e9rcito II y bandas militares<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>25.08.2023 &#8211; Hoy, se realizaron los actos protocolares por el 198\u00ba aniversario de la Declaratoria de la Independencia.<\/p>\n","protected":false},"author":15,"featured_media":24520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2,10,14],"tags":[],"class_list":["post-24519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-destacados","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/24519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/comments?post=24519"}],"version-history":[{"count":8,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/24519\/revisions"}],"predecessor-version":[{"id":24669,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/24519\/revisions\/24669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media\/24520"}],"wp:attachment":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media?parent=24519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/categories?post=24519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/tags?post=24519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}