{"id":6695,"date":"2021-10-02T10:33:36","date_gmt":"2021-10-02T13:33:36","guid":{"rendered":"https:\/\/www.ejercito.mil.uy\/?p=6695"},"modified":"2021-10-03T10:33:40","modified_gmt":"2021-10-03T13:33:40","slug":"apoyo-a-familias-evacuadas-2","status":"publish","type":"post","link":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/","title":{"rendered":"Apoyo a familias evacuadas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">02.10.2021 &#8211; R\u00edo Branco, Cerro Largo<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas atr\u00e1s, efectivos del <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/Reg.c.mec7\/\" target=\"_blank\">Regimiento \u00abGral. Aparicio Saravia\u00bb de Caballer\u00eda Mecanizado N\u00b0 7<\/a><\/strong> trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar, que a su vez, la Unidad realiz\u00f3 la evacuaci\u00f3n y a diario confeccionaba y distribu\u00eda el desayuno y merienda para las 6 familias, mientras que estuvieron fuera de sus hogares.<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>\u00a1Muchas gracias camaradas!<\/strong><\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-coblocks-gallery-carousel\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg\" style=\"height:400px\" data-flickity=\"{&quot;autoPlay&quot;:4000,&quot;draggable&quot;:true,&quot;pageDots&quot;:true,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;center&quot;,&quot;pauseAutoPlayOnHover&quot;:true,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:false}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-1-1024x683.jpg\" alt=\"\" data-id=\"6697\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=6697\" class=\"wp-image-6697\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-1-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-1-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-2-1024x683.jpg\" alt=\"\" data-id=\"6698\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=6698\" class=\"wp-image-6698\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-2-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-2-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-3-1024x683.jpg\" alt=\"\" data-id=\"6699\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=6699\" class=\"wp-image-6699\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-3-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-3-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-3.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-4-1024x683.jpg\" alt=\"\" data-id=\"6700\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=6700\" class=\"wp-image-6700\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-4-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-4-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-4.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-5-1024x683.jpg\" alt=\"\" data-id=\"6701\" data-link=\"https:\/\/www.ejercito.mil.uy\/?attachment_id=6701\" class=\"wp-image-6701\" srcset=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-5-1024x683.jpg 1024w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-5-300x200.jpg 300w, https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados-5.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<div style=\"height:66px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>02.10.2021 &#8211; D\u00edas atr\u00e1s, efectivos del Regimiento \u00abGral. Aparicio Saravia\u00bb de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.<\/p>\n","protected":false},"author":4,"featured_media":6702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2,14],"tags":[36,27,32,29,49,28,37],"class_list":["post-6695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-noticias","tag-alimentacion","tag-apoyo","tag-bienestar","tag-comunidad","tag-inundaciones","tag-social","tag-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento &quot;Gral. Aparicio Saravia&quot; de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alejandro Castro\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ej\u00e9rcito Nacional - La Fuerza de todos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional\" \/>\n\t\t<meta property=\"og:description\" content=\"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento &quot;Gral. Aparicio Saravia&quot; de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"134\" \/>\n\t\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-02T13:33:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-10-03T13:33:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional\" \/>\n\t\t<meta name=\"twitter:description\" content=\"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento &quot;Gral. Aparicio Saravia&quot; de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#blogposting\",\"name\":\"Apoyo a familias evacuadas - Ej\\u00e9rcito Nacional\",\"headline\":\"Apoyo a familias evacuadas\",\"author\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/acastro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Evacuados.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Evacuados\"},\"datePublished\":\"2021-10-02T10:33:36-03:00\",\"dateModified\":\"2021-10-03T10:33:40-03:00\",\"inLanguage\":\"es-UY\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#webpage\"},\"articleSection\":\"Blog, Noticias, alimentaci\\u00f3n, apoyo, bienestar, comunidad, inundaciones, social, sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"name\":\"Destacados\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"position\":2,\"name\":\"Destacados\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#listItem\",\"name\":\"Apoyo a familias evacuadas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"name\":\"Destacados\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#listItem\",\"position\":4,\"name\":\"Apoyo a familias evacuadas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\",\"name\":\"Ej\\u00e9rcito Nacional\",\"description\":\"La Fuerza de todos\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Escudo_EN_URUGUAY.png\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#organizationLogo\",\"width\":134,\"height\":119},\"image\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/acastro\\\/#author\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/acastro\\\/\",\"name\":\"Alejandro Castro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89bb77d4bf696501dd94ca89e6794e1787eaffba7c7197528d249e15bd099f68?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alejandro Castro\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/\",\"name\":\"Apoyo a familias evacuadas - Ej\\u00e9rcito Nacional\",\"description\":\"02.10.2021 - D\\u00edas atr\\u00e1s, efectivos del Regimiento \\\"Gral. Aparicio Saravia\\\" de Caballer\\u00eda Mecanizado N\\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\\u00ed debido a la creciente del caudal del R\\u00edo Yaguar\\u00f3n.\",\"inLanguage\":\"es-UY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/acastro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/acastro\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Evacuados.jpg\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#mainImage\",\"width\":1200,\"height\":800,\"caption\":\"Evacuados\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/10\\\/02\\\/apoyo-a-familias-evacuadas-2\\\/#mainImage\"},\"datePublished\":\"2021-10-02T10:33:36-03:00\",\"dateModified\":\"2021-10-03T10:33:40-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#website\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/\",\"name\":\"Ej\\u00e9rcito Nacional\",\"description\":\"La Fuerza de todos\",\"inLanguage\":\"es-UY\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional","description":"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento \"Gral. Aparicio Saravia\" de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.","canonical_url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#blogposting","name":"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional","headline":"Apoyo a familias evacuadas","author":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/acastro\/#author"},"publisher":{"@id":"https:\/\/www.ejercito.mil.uy\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados.jpg","width":1200,"height":800,"caption":"Evacuados"},"datePublished":"2021-10-02T10:33:36-03:00","dateModified":"2021-10-03T10:33:40-03:00","inLanguage":"es-UY","mainEntityOfPage":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#webpage"},"articleSection":"Blog, Noticias, alimentaci\u00f3n, apoyo, bienestar, comunidad, inundaciones, social, sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy#listItem","position":1,"name":"Home","item":"https:\/\/www.ejercito.mil.uy","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","name":"Destacados"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","position":2,"name":"Destacados","item":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","name":"Noticias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","position":3,"name":"Noticias","item":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#listItem","name":"Apoyo a familias evacuadas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","name":"Destacados"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#listItem","position":4,"name":"Apoyo a familias evacuadas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/www.ejercito.mil.uy\/#organization","name":"Ej\u00e9rcito Nacional","description":"La Fuerza de todos","url":"https:\/\/www.ejercito.mil.uy\/","logo":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#organizationLogo","width":134,"height":119},"image":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/acastro\/#author","url":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/acastro\/","name":"Alejandro Castro","image":{"@type":"ImageObject","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/89bb77d4bf696501dd94ca89e6794e1787eaffba7c7197528d249e15bd099f68?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alejandro Castro"}},{"@type":"WebPage","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#webpage","url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/","name":"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional","description":"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento \"Gral. Aparicio Saravia\" de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.","inLanguage":"es-UY","isPartOf":{"@id":"https:\/\/www.ejercito.mil.uy\/#website"},"breadcrumb":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/acastro\/#author"},"creator":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/acastro\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/10\/Evacuados.jpg","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#mainImage","width":1200,"height":800,"caption":"Evacuados"},"primaryImageOfPage":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/#mainImage"},"datePublished":"2021-10-02T10:33:36-03:00","dateModified":"2021-10-03T10:33:40-03:00"},{"@type":"WebSite","@id":"https:\/\/www.ejercito.mil.uy\/#website","url":"https:\/\/www.ejercito.mil.uy\/","name":"Ej\u00e9rcito Nacional","description":"La Fuerza de todos","inLanguage":"es-UY","publisher":{"@id":"https:\/\/www.ejercito.mil.uy\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ej\u00e9rcito Nacional - La Fuerza de todos","og:type":"article","og:title":"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional","og:description":"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento &quot;Gral. Aparicio Saravia&quot; de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.","og:url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/","og:image":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","og:image:secure_url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","og:image:width":134,"og:image:height":119,"article:published_time":"2021-10-02T13:33:36+00:00","article:modified_time":"2021-10-03T13:33:40+00:00","twitter:card":"summary_large_image","twitter:title":"Apoyo a familias evacuadas - Ej\u00e9rcito Nacional","twitter:description":"02.10.2021 - D\u00edas atr\u00e1s, efectivos del Regimiento &quot;Gral. Aparicio Saravia&quot; de Caballer\u00eda Mecanizado N\u00b0 7 trasladaron a los compatriotas evacuados y sus pertenencias desde el Gimnasio Municipal hacia sus hogares en la zona comercial, se encontraban alojadas all\u00ed debido a la creciente del caudal del R\u00edo Yaguar\u00f3n.","twitter:image":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png"},"aioseo_meta_data":{"post_id":"6695","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-08-30 02:18:33","updated":"2025-08-30 02:18:33","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/\" title=\"Destacados\">Destacados<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tApoyo a familias evacuadas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ejercito.mil.uy"},{"label":"Destacados","link":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/"},{"label":"Noticias","link":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/"},{"label":"Apoyo a familias evacuadas","link":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/10\/02\/apoyo-a-familias-evacuadas-2\/"}],"_links":{"self":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/6695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/comments?post=6695"}],"version-history":[{"count":2,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/6695\/revisions"}],"predecessor-version":[{"id":6703,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/6695\/revisions\/6703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media\/6702"}],"wp:attachment":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media?parent=6695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/categories?post=6695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/tags?post=6695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}