{"id":7882,"date":"2021-11-11T08:00:00","date_gmt":"2021-11-11T11:00:00","guid":{"rendered":"https:\/\/www.ejercito.mil.uy\/?p=7882"},"modified":"2021-11-23T09:52:52","modified_gmt":"2021-11-23T12:52:52","slug":"calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre","status":"publish","type":"post","link":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/","title":{"rendered":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">11.11.2021<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Del 15 al 14 de noviembre, el <strong>Servicio de Material y Armamento<\/strong>, a trav\u00e9s del <strong>Registro Nacional de Armas (RNA)<\/strong>, estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (<strong>Regimiento de Caballer\u00eda Blindado N\u00ba 8<\/strong>) y Treinta y Tres (<strong><a href=\"https:\/\/www.facebook.com\/BatallondeInfateriaN10Uy\" target=\"_blank\" rel=\"noreferrer noopener\">Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10<\/a><\/strong>).<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La finalidad de estas visitas es que la poblaci\u00f3n pueda realizar los tr\u00e1mites pertinentes a la transferencia y\/o registro de armas usadas, presentando la siguiente documentaci\u00f3n:  <\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br> <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udccc\" src=\"https:\/\/www.facebook.com\/images\/emoji.php\/v9\/t4b\/2\/16\/1f4cc.png\"> fotocopia de CI <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udccc\" src=\"https:\/\/www.facebook.com\/images\/emoji.php\/v9\/t4b\/2\/16\/1f4cc.png\"> fotocopia constancia de domicilio <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udccc\" src=\"https:\/\/www.facebook.com\/images\/emoji.php\/v9\/t4b\/2\/16\/1f4cc.png\"> fotocopia del T\u00edtulo de Habilitaci\u00f3n para la Adquisici\u00f3n y Tenencia de Armas (THATA) <\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br> <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u260e\" src=\"https:\/\/www.facebook.com\/images\/emoji.php\/v9\/ta3\/2\/16\/260e.png\"> Por m\u00e1s informaci\u00f3n comunicarse con el RNA de lunes a viernes de 8 a 13 h, al <strong>2355 3434<\/strong> int. <strong>114<\/strong> o <strong>091 000 065<\/strong> (coleccionistas).<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>11.11.2021 &#8211; Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).<\/p>\n","protected":false},"author":15,"featured_media":7883,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2,14],"tags":[],"class_list":["post-7882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Tel\u00e9fono de Servicio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ej\u00e9rcito Nacional - La Fuerza de todos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional\" \/>\n\t\t<meta property=\"og:description\" content=\"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"134\" \/>\n\t\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-11T11:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-11-23T12:52:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional\" \/>\n\t\t<meta name=\"twitter:description\" content=\"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#blogposting\",\"name\":\"Calendario de actividades del RNA m\\u00f3vil hasta el 19 de noviembre - Ej\\u00e9rcito Nacional\",\"headline\":\"Calendario de actividades del RNA m\\u00f3vil hasta el 19 de noviembre\",\"author\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/cominstitucional\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RNA_NOV_Melo-TyT.jpg\",\"width\":1200,\"height\":800},\"datePublished\":\"2021-11-11T08:00:00-03:00\",\"dateModified\":\"2021-11-23T09:52:52-03:00\",\"inLanguage\":\"es-UY\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#webpage\"},\"articleSection\":\"Blog, Noticias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"name\":\"Destacados\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"position\":2,\"name\":\"Destacados\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#listItem\",\"name\":\"Calendario de actividades del RNA m\\u00f3vil hasta el 19 de noviembre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/#listItem\",\"name\":\"Destacados\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#listItem\",\"position\":4,\"name\":\"Calendario de actividades del RNA m\\u00f3vil hasta el 19 de noviembre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/category\\\/destacados\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\",\"name\":\"Ej\\u00e9rcito Nacional\",\"description\":\"La Fuerza de todos\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Escudo_EN_URUGUAY.png\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#organizationLogo\",\"width\":134,\"height\":119},\"image\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/cominstitucional\\\/#author\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/cominstitucional\\\/\",\"name\":\"Tel\\u00e9fono de Servicio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/634cc335793368ccef18974dca19ed6cda05733bc6a5358ec0bab1b2b28c2879?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Tel\\u00e9fono de Servicio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/\",\"name\":\"Calendario de actividades del RNA m\\u00f3vil hasta el 19 de noviembre - Ej\\u00e9rcito Nacional\",\"description\":\"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\\u00e9s del Registro Nacional de Armas (RNA), estar\\u00e1 desplegando sus oficinas m\\u00f3viles en los departamentos de Melo (Regimiento de Caballer\\u00eda Blindado N\\u00ba 8) y Treinta y Tres (Batall\\u00f3n de Infanter\\u00eda Mecanizado N\\u00ba 10).\",\"inLanguage\":\"es-UY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/cominstitucional\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/author\\\/cominstitucional\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RNA_NOV_Melo-TyT.jpg\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#mainImage\",\"width\":1200,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/index.php\\\/2021\\\/11\\\/11\\\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\\\/#mainImage\"},\"datePublished\":\"2021-11-11T08:00:00-03:00\",\"dateModified\":\"2021-11-23T09:52:52-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#website\",\"url\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/\",\"name\":\"Ej\\u00e9rcito Nacional\",\"description\":\"La Fuerza de todos\",\"inLanguage\":\"es-UY\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ejercito.mil.uy\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional","description":"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).","canonical_url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#blogposting","name":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional","headline":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre","author":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/cominstitucional\/#author"},"publisher":{"@id":"https:\/\/www.ejercito.mil.uy\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/11\/RNA_NOV_Melo-TyT.jpg","width":1200,"height":800},"datePublished":"2021-11-11T08:00:00-03:00","dateModified":"2021-11-23T09:52:52-03:00","inLanguage":"es-UY","mainEntityOfPage":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#webpage"},"articleSection":"Blog, Noticias"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy#listItem","position":1,"name":"Home","item":"https:\/\/www.ejercito.mil.uy","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","name":"Destacados"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","position":2,"name":"Destacados","item":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","name":"Noticias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","position":3,"name":"Noticias","item":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#listItem","name":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/#listItem","name":"Destacados"}},{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#listItem","position":4,"name":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/www.ejercito.mil.uy\/#organization","name":"Ej\u00e9rcito Nacional","description":"La Fuerza de todos","url":"https:\/\/www.ejercito.mil.uy\/","logo":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#organizationLogo","width":134,"height":119},"image":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/cominstitucional\/#author","url":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/cominstitucional\/","name":"Tel\u00e9fono de Servicio","image":{"@type":"ImageObject","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/634cc335793368ccef18974dca19ed6cda05733bc6a5358ec0bab1b2b28c2879?s=96&d=mm&r=g","width":96,"height":96,"caption":"Tel\u00e9fono de Servicio"}},{"@type":"WebPage","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#webpage","url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/","name":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional","description":"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).","inLanguage":"es-UY","isPartOf":{"@id":"https:\/\/www.ejercito.mil.uy\/#website"},"breadcrumb":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/cominstitucional\/#author"},"creator":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/author\/cominstitucional\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2021\/11\/RNA_NOV_Melo-TyT.jpg","@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#mainImage","width":1200,"height":800},"primaryImageOfPage":{"@id":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/#mainImage"},"datePublished":"2021-11-11T08:00:00-03:00","dateModified":"2021-11-23T09:52:52-03:00"},{"@type":"WebSite","@id":"https:\/\/www.ejercito.mil.uy\/#website","url":"https:\/\/www.ejercito.mil.uy\/","name":"Ej\u00e9rcito Nacional","description":"La Fuerza de todos","inLanguage":"es-UY","publisher":{"@id":"https:\/\/www.ejercito.mil.uy\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ej\u00e9rcito Nacional - La Fuerza de todos","og:type":"article","og:title":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional","og:description":"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).","og:url":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/","og:image":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","og:image:secure_url":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png","og:image:width":134,"og:image:height":119,"article:published_time":"2021-11-11T11:00:00+00:00","article:modified_time":"2021-11-23T12:52:52+00:00","twitter:card":"summary_large_image","twitter:title":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre - Ej\u00e9rcito Nacional","twitter:description":"11.11.2021 - Del 15 al 14 de noviembre, el Servicio de Material y Armamento, a trav\u00e9s del Registro Nacional de Armas (RNA), estar\u00e1 desplegando sus oficinas m\u00f3viles en los departamentos de Melo (Regimiento de Caballer\u00eda Blindado N\u00ba 8) y Treinta y Tres (Batall\u00f3n de Infanter\u00eda Mecanizado N\u00ba 10).","twitter:image":"https:\/\/www.ejercito.mil.uy\/wp-content\/uploads\/2022\/01\/Escudo_EN_URUGUAY.png"},"aioseo_meta_data":{"post_id":"7882","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-08-30 02:25:40","updated":"2025-08-30 02:25:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/\" title=\"Destacados\">Destacados<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCalendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ejercito.mil.uy"},{"label":"Destacados","link":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/"},{"label":"Noticias","link":"https:\/\/www.ejercito.mil.uy\/index.php\/category\/destacados\/noticias\/"},{"label":"Calendario de actividades del RNA m\u00f3vil hasta el 19 de noviembre","link":"https:\/\/www.ejercito.mil.uy\/index.php\/2021\/11\/11\/calendario-de-actividades-del-rna-movil-hasta-el-19-de-noviembre\/"}],"_links":{"self":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/7882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/comments?post=7882"}],"version-history":[{"count":1,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/7882\/revisions"}],"predecessor-version":[{"id":7884,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/posts\/7882\/revisions\/7884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media\/7883"}],"wp:attachment":[{"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/media?parent=7882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/categories?post=7882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ejercito.mil.uy\/index.php\/wp-json\/wp\/v2\/tags?post=7882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}